{"id":2199,"date":"2018-05-24T00:00:00","date_gmt":"2018-05-23T22:00:00","guid":{"rendered":"https:\/\/www.fondazioneunipolis.org\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/"},"modified":"2026-01-05T14:33:40","modified_gmt":"2026-01-05T13:33:40","slug":"bando-culturability-2018-selezionati-i-15-finalisti","status":"publish","type":"post","link":"https:\/\/www.fondazioneunipolis.org\/site\/news\/bando-culturability-2018-selezionati-i-15-finalisti\/","title":{"rendered":"Bando culturability 2018 selezionati i 15 finalisti"},"content":{"rendered":"<div id=\"ctl00_PlaceHolderMain_ctl03__ControlWrapper_RichHtmlField\" class=\"ms-rtestate-field\" style=\"display: inline;\" aria-labelledby=\"ctl00_PlaceHolderMain_ctl03_label\">\n<p>\u200bPalazzi storici vuoti, fabbriche e spazi industriali dismessi, edifici pubblici e spazi ferroviari inutilizzati, biblioteche chiuse, conventi e chiese dimenticati, aree aperte che riprendono vita, rinascendo come luoghi di cultura e di comunit\u00e0: queste le sfide lanciate dai<strong>\u00a015 finalisti\u00a0<\/strong>selezionati con il bando 2018\u00a0<strong><em><a href=\"https:\/\/www.fondazioneunipolis.org\/site\/progetti\/culturability-4\/\" target=\"_blank\" rel=\"noopener\">culturability<\/a> \u2013 rigenerare spazi da condividere<\/em><\/strong>, scelti fra i\u00a0<strong>341 progetti candidati da tutta Italia<\/strong>\u00a0alla call, promossa dalla\u00a0<strong>Fondazione Unipolis<\/strong>, per sostenere iniziative culturali e creative innovative ad alto impatto sociale che rigenerano e riattivano spazi.<\/p>\n<p><strong>Il budget complessivo del bando \u00e8 pari a\u00a0450 mila euro per progetti culturali innovativi ad alto impatto sociale<\/strong>\u00a0che rigenerano e danno nuova vita a spazi, edifici, ex siti industriali, abbandonati o sottoutilizzati. Cultura, innovazione e coesione sociale, collaborazione, sostenibilit\u00e0, occupazione giovanile: questi gli ingredienti chiesti per riempire di creativit\u00e0 questi vuoti e restituirli alle comunit\u00e0 territoriali di riferimento.<\/p>\n<p>Il processo di selezione non \u00e8 stato semplice, considerato il numero, la qualit\u00e0 e la visione dei partecipanti.\u00a0<strong>Oltre il 50% dei progetti scelti arriva dal sud e dalle isole<\/strong>, da queste regioni sono non solo numerose ma anche di grande valore le iniziative pervenute.<\/p>\n<p><strong>Questi i progetti e la loro collocazione geografica<\/strong><strong><em>:<\/em><\/strong><\/p>\n<p><em>Badia Lost &amp; Found<\/em>\u00a0| Lentini (Siracusa)<br \/>\n<em>BIP \u2013 Ballo In Piazza<\/em>\u00a0| Lucca<br \/>\n<em>ConMe \u2013 Convento Meridiano<\/em>\u00a0| Cerreto Sannita (Benevento)<br \/>\n<em>Da grande sar\u00f2 un teatro!<\/em>\u00a0| San Vito dei Normanni (Brindisi)<br \/>\n<em>DLF \u2013 Dove Liberare Futuro<\/em>\u00a0| Bologna<br \/>\n<em>ExSA sunt communia | Leg\u00e0mi in evoluzione<\/em>\u00a0| Bergamo<br \/>\n<em>Fare Scuola | L&#8217;insegnamento di Cesare Leonardi nel Villaggio Artigiano di Modena Ovest<\/em>\u00a0| Modena<br \/>\n<em>FontegoHub \u2013 Il primo Cultural Hub a Venezia\u00a0<\/em>| Venezia<br \/>\n<em>Giovani Open Space (GOS) \u2013 Distillerie Culturali\u00a0<\/em>| Barletta<br \/>\n<em>Imbarchino, molto pi\u00f9 di un luogo comune\u00a0<\/em>| Torino<br \/>\n<em>LANDWORKS PLUS IN-SEGNARE il paesaggio<\/em>\u00a0| Sassari<br \/>\n<em>Le officine delle idee<\/em>\u00a0| Pisa<br \/>\n<em>Roma Smistamento<\/em>\u00a0| Roma<br \/>\n<em>Spazio 13<\/em>\u00a0| Bari<br \/>\n<em>Spazio Franco<\/em>\u00a0| Palermo<\/p>\n<p>A seguito di questa prima selezione, i finalisti sono ammessi al\u00a0<strong>percorso di supporto e accompagnamento<\/strong>\u00a0finalizzato a migliorare e sviluppare le proposte, che dovranno essere poi rinviate a Unipolis entro il 2 agosto. Tra queste, nel mese di settembre, una Commissione di esperti selezioner\u00e0\u00a0<strong>6 progetti che riceveranno 50 mila euro ciascuno e continueranno l&#8217;attivit\u00e0 di\u00a0<\/strong><em><strong>mentoring<\/strong><\/em>. Il budget complessivo del bando \u00e8 pari a\u00a0<strong>450 mila euro\u00a0<\/strong>tra contributi economici per lo sviluppo delle iniziative, percorso di accompagnamento per l&#8217;<em>empowerment<\/em>\u00a0dei team e rimborsi spese per partecipare alle attivit\u00e0. Ai 400 mila euro stanziati da Fondazione Unipolis, si aggiunge un contributo della\u00a0<strong>Direzione Generale Arte e Architettura Contemporanee e Periferie Urbane del MiBACT\u00a0<\/strong>che mette a disposizione risorse economiche che consentiranno di selezionare un sesto progetto tra i 15 finalisti. Anche per questa edizione del bando, il percorso di\u00a0<em>mentoring<\/em>\u00a0sar\u00e0 seguito da\u00a0<a href=\"http:\/\/www.avanzi.org\/\"><strong>Avanzi<\/strong><\/a><strong>\/<\/strong><a href=\"http:\/\/makeacube.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Make a Cube\u00b3<\/strong><\/a>\u00a0e\u00a0<a href=\"http:\/\/www.fitzcarraldo.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Fondazione Fitzcarraldo<\/strong><\/a>, partner dell&#8217;iniziativa.<\/p>\n<p>Gi\u00e0 negli scorsi anni,\u00a0<em>culturability<\/em>\u00a0ha riscontrato ottimi risultati di partecipazione, in termini di progetti aderenti e di qualit\u00e0 delle proposte, come dimostrato dai successi delle realt\u00e0 sostenute che continuano i loro percorsi di sviluppo. Complessivamente, per le cinque edizioni Fondazione Unipolis ha investito\u00a0<strong>oltre un milione e 800 mila euro e 3.112 sono stati i progetti partecipanti<\/strong>.<\/p>\n<p>Per ulteriori informazioni sui selezionati si rimanda alla <a href=\"https:\/\/www.fondazioneunipolis.org\/site\/progetti\/culturability-4\/\" target=\"_blank\" rel=\"noopener\"><strong>pagina di culturability<\/strong><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u200bPalazzi storici vuoti, fabbriche e spazi industriali dismessi, edifici pubblici e spazi ferroviari inutilizzati, biblioteche chiuse, conventi e chiese dimenticati, aree aperte che riprendono vita, rinascendo come luoghi di cultura e di comunit\u00e0: queste le sfide lanciate dai\u00a015 finalisti\u00a0selezionati con il bando 2018\u00a0culturability \u2013 rigenerare spazi da condividere, scelti fra i\u00a0341 progetti candidati da tutta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[642,671],"class_list":["post-2199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unipolis","tag-culturability_programma","tag-culturability5"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bando culturability 2018 selezionati i 15 finalisti - Unipolis<\/title>\n<meta name=\"description\" content=\"Bando culturability 2018 selezionati i 15 finalisti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondazioneunipolis.org\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando culturability 2018 selezionati i 15 finalisti - Unipolis\" \/>\n<meta property=\"og:description\" content=\"Bando culturability 2018 selezionati i 15 finalisti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\" \/>\n<meta property=\"og:site_name\" content=\"Unipolis\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T13:33:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wsadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wsadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\"},\"author\":{\"name\":\"wsadmin\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/43819ef7aaa5af51f1ed547eacb5e868\"},\"headline\":\"Bando culturability 2018 selezionati i 15 finalisti\",\"datePublished\":\"2018-05-23T22:00:00+00:00\",\"dateModified\":\"2026-01-05T13:33:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg\",\"keywords\":[\"culturability_programma\",\"culturability5\"],\"articleSection\":[\"Unipolis\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\",\"url\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\",\"name\":\"Bando culturability 2018 selezionati i 15 finalisti - Unipolis\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg\",\"datePublished\":\"2018-05-23T22:00:00+00:00\",\"dateModified\":\"2026-01-05T13:33:40+00:00\",\"description\":\"Bando culturability 2018 selezionati i 15 finalisti\",\"breadcrumb\":{\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage\",\"url\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg\",\"contentUrl\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondazioneunipolis.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando culturability 2018 selezionati i 15 finalisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#website\",\"url\":\"https:\/\/www.fondazioneunipolis.org\/site\/\",\"name\":\"Unipolis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondazioneunipolis.org\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#organization\",\"name\":\"Unipolis\",\"url\":\"https:\/\/www.fondazioneunipolis.org\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/2025\/07\/logo-fondazione-unipolis-1.svg\",\"contentUrl\":\"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/2025\/07\/logo-fondazione-unipolis-1.svg\",\"caption\":\"Unipolis\"},\"image\":{\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/43819ef7aaa5af51f1ed547eacb5e868\",\"name\":\"wsadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6512509e9ae62b647044a2731fadcbf236f2546df7b086feb6df7aabf2ef03aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6512509e9ae62b647044a2731fadcbf236f2546df7b086feb6df7aabf2ef03aa?s=96&d=mm&r=g\",\"caption\":\"wsadmin\"},\"sameAs\":[\"https:\/\/www.fondazioneunipolis.org\/site\"],\"url\":\"https:\/\/www.fondazioneunipolis.org\/site\/author\/wsadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando culturability 2018 selezionati i 15 finalisti - Unipolis","description":"Bando culturability 2018 selezionati i 15 finalisti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondazioneunipolis.org\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/","og_locale":"it_IT","og_type":"article","og_title":"Bando culturability 2018 selezionati i 15 finalisti - Unipolis","og_description":"Bando culturability 2018 selezionati i 15 finalisti","og_url":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/","og_site_name":"Unipolis","article_published_time":"2018-05-23T22:00:00+00:00","article_modified_time":"2026-01-05T13:33:40+00:00","og_image":[{"url":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"wsadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wsadmin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#article","isPartOf":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/"},"author":{"name":"wsadmin","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/43819ef7aaa5af51f1ed547eacb5e868"},"headline":"Bando culturability 2018 selezionati i 15 finalisti","datePublished":"2018-05-23T22:00:00+00:00","dateModified":"2026-01-05T13:33:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/www.fondazioneunipolis.org\/site\/#organization"},"image":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg","keywords":["culturability_programma","culturability5"],"articleSection":["Unipolis"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/","url":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/","name":"Bando culturability 2018 selezionati i 15 finalisti - Unipolis","isPartOf":{"@id":"https:\/\/www.fondazioneunipolis.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage"},"image":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg","datePublished":"2018-05-23T22:00:00+00:00","dateModified":"2026-01-05T13:33:40+00:00","description":"Bando culturability 2018 selezionati i 15 finalisti","breadcrumb":{"@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#primaryimage","url":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg","contentUrl":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/import\/PublishingImages\/Notizie\/cult_banner_fondunip_830x390.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dx-factory-unipolis-corporate-wp.ha.servizi.gr-u.it\/site\/bando-culturability-2018-selezionati-i-15-finalisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondazioneunipolis.org\/site\/"},{"@type":"ListItem","position":2,"name":"Bando culturability 2018 selezionati i 15 finalisti"}]},{"@type":"WebSite","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#website","url":"https:\/\/www.fondazioneunipolis.org\/site\/","name":"Unipolis","description":"","publisher":{"@id":"https:\/\/www.fondazioneunipolis.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondazioneunipolis.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#organization","name":"Unipolis","url":"https:\/\/www.fondazioneunipolis.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/2025\/07\/logo-fondazione-unipolis-1.svg","contentUrl":"https:\/\/www.fondazioneunipolis.org\/site\/wp-content\/uploads\/2025\/07\/logo-fondazione-unipolis-1.svg","caption":"Unipolis"},"image":{"@id":"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/43819ef7aaa5af51f1ed547eacb5e868","name":"wsadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fondazioneunipolis.org\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6512509e9ae62b647044a2731fadcbf236f2546df7b086feb6df7aabf2ef03aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6512509e9ae62b647044a2731fadcbf236f2546df7b086feb6df7aabf2ef03aa?s=96&d=mm&r=g","caption":"wsadmin"},"sameAs":["https:\/\/www.fondazioneunipolis.org\/site"],"url":"https:\/\/www.fondazioneunipolis.org\/site\/author\/wsadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/posts\/2199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/comments?post=2199"}],"version-history":[{"count":5,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/posts\/2199\/revisions"}],"predecessor-version":[{"id":11646,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/posts\/2199\/revisions\/11646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/media\/4289"}],"wp:attachment":[{"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/media?parent=2199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/categories?post=2199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondazioneunipolis.org\/site\/wp-json\/wp\/v2\/tags?post=2199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}